{"id":28499,"date":"2026-03-31T16:53:18","date_gmt":"2026-03-31T14:53:18","guid":{"rendered":"https:\/\/www.ecotechnology.at\/?post_type=termine&#038;p=28499"},"modified":"2026-03-31T16:58:10","modified_gmt":"2026-03-31T14:58:10","slug":"8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht","status":"publish","type":"termine","link":"https:\/\/www.ecotechnology.at\/en\/termine\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\/","title":{"rendered":"8. Nachhaltigkeitsbrunch &#8211; ESG 2026: Wie aus Reporting Wirkung entsteht"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"28499\" class=\"elementor elementor-28499\" data-elementor-post-type=\"termine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3652bc20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3652bc20\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3520a70d\" data-id=\"3520a70d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13c226a elementor-widget elementor-widget-heading\" data-id=\"13c226a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><b>Die O\u00d6 Leitveranstaltung im Nachhaltigkeitsmanagement<\/b><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19dae63a elementor-widget elementor-widget-text-editor\" data-id=\"19dae63a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Format bleibt kompakt und dialogorientiert \u2013 mit Kurzimpulsen, Best-Practice-Einblicken und Networking.<\/p>\n<p>Die Bedeutung von ESG bleibt unbestritten &#8211; doch gerade jetzt braucht es Orientierung: Berichtspflichten und Deregulierung verunsichern, w\u00e4hrend der Anspruch von Investoren, ESG-Teams und Gesch\u00e4ftspartnern steigt. Unser 8. Nachhaltigkeitsbrunch richtet den Blick bewusst nach vorne und bringt Klarheit.<\/p>\n<p>Was hat sich durch Omnibus und NaBeG ge\u00e4ndert? Wie freiwillig ist der VSME wirklich, und worauf kommt es in der Umsetzung an? Welche EU-Regulierungen stehen noch bevor, und sind Sie f\u00fcr CBAM &amp; Co ger\u00fcstet? Wie geben Banken den regulatorischen Druck an ihre Kund:innen weiter? Wie gelingt die wirksame Integration von ESG in Unternehmensstrategie, Managementsysteme und Kommunikation?<\/p>\n<p>In bew\u00e4hrter Manier trifft sich die Community: Wir diskutieren L\u00f6sungsans\u00e4tze, kl\u00e4ren die dr\u00e4ngendsten ESG-Fragen, blicken in die Unternehmenspraxis.<\/p>\n<p>&gt;<a href=\"https:\/\/www.biz-up.at\/veranstaltung\/8-nachhaltigkeitsbrunch-21-04-2026\" target=\"_blank\" style=\"background-color: rgb(255, 255, 255);\">&gt; Programm &amp; Anmeldung<\/a><\/p>\n<p><u>Geb\u00fchren:<br><\/u>Partner in einem Cluster oder Netzwerk: \u20ac 135,-<br>Regul\u00e4rer Preis: \u20ac 200,-<\/p>\n<p><i>Teilnahmegeb\u00fchr (alle Preise exkl. MwSt.)<br><\/i>ANMELDESCHLUSS: 13. April 2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"template":"","termin_category":[],"cmcal_calendar":[],"class_list":["post-28499","termine","type-termine","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8. Nachhaltigkeitsbrunch - ESG 2026: Wie aus Reporting Wirkung entsteht - ecotechnology<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecotechnology.at\/en\/termine\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8. Nachhaltigkeitsbrunch - ESG 2026: Wie aus Reporting Wirkung entsteht - ecotechnology\" \/>\n<meta property=\"og:description\" content=\"Die O\u00d6 Leitveranstaltung im Nachhaltigkeitsmanagement Das Format bleibt kompakt und dialogorientiert \u2013 mit Kurzimpulsen, Best-Practice-Einblicken und Networking. Die Bedeutung von ESG bleibt unbestritten &#8211; doch gerade jetzt braucht es Orientierung: Berichtspflichten und Deregulierung verunsichern, w\u00e4hrend der Anspruch von Investoren, ESG-Teams und Gesch\u00e4ftspartnern steigt. Unser 8. Nachhaltigkeitsbrunch richtet den Blick bewusst nach vorne und bringt Klarheit. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecotechnology.at\/en\/termine\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\/\" \/>\n<meta property=\"og:site_name\" content=\"ecotechnology\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T14:58:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/termine\\\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\\\/\",\"url\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/termine\\\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\\\/\",\"name\":\"8. Nachhaltigkeitsbrunch - ESG 2026: Wie aus Reporting Wirkung entsteht - ecotechnology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/#website\"},\"datePublished\":\"2026-03-31T14:53:18+00:00\",\"dateModified\":\"2026-03-31T14:58:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/termine\\\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/termine\\\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/termine\\\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Termine\",\"item\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/termine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"8. Nachhaltigkeitsbrunch &#8211; ESG 2026: Wie aus Reporting Wirkung entsteht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/\",\"name\":\"ecotechnology\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/#organization\",\"name\":\"ecotechnology\",\"url\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ecotechnology.at\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/ecolinks_logo_0.png\",\"contentUrl\":\"https:\\\/\\\/www.ecotechnology.at\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/ecolinks_logo_0.png\",\"width\":336,\"height\":128,\"caption\":\"ecotechnology\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ecotechnology.at\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8. Nachhaltigkeitsbrunch - ESG 2026: Wie aus Reporting Wirkung entsteht - ecotechnology","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecotechnology.at\/en\/termine\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\/","og_locale":"en_US","og_type":"article","og_title":"8. Nachhaltigkeitsbrunch - ESG 2026: Wie aus Reporting Wirkung entsteht - ecotechnology","og_description":"Die O\u00d6 Leitveranstaltung im Nachhaltigkeitsmanagement Das Format bleibt kompakt und dialogorientiert \u2013 mit Kurzimpulsen, Best-Practice-Einblicken und Networking. Die Bedeutung von ESG bleibt unbestritten &#8211; doch gerade jetzt braucht es Orientierung: Berichtspflichten und Deregulierung verunsichern, w\u00e4hrend der Anspruch von Investoren, ESG-Teams und Gesch\u00e4ftspartnern steigt. Unser 8. Nachhaltigkeitsbrunch richtet den Blick bewusst nach vorne und bringt Klarheit. [&hellip;]","og_url":"https:\/\/www.ecotechnology.at\/en\/termine\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\/","og_site_name":"ecotechnology","article_modified_time":"2026-03-31T14:58:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecotechnology.at\/en\/termine\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\/","url":"https:\/\/www.ecotechnology.at\/en\/termine\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\/","name":"8. Nachhaltigkeitsbrunch - ESG 2026: Wie aus Reporting Wirkung entsteht - ecotechnology","isPartOf":{"@id":"https:\/\/www.ecotechnology.at\/en\/#website"},"datePublished":"2026-03-31T14:53:18+00:00","dateModified":"2026-03-31T14:58:10+00:00","breadcrumb":{"@id":"https:\/\/www.ecotechnology.at\/en\/termine\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecotechnology.at\/en\/termine\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecotechnology.at\/en\/termine\/8-nachhaltigkeitsbrunch-esg-2026-wie-aus-reporting-wirkung-entsteht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecotechnology.at\/en\/"},{"@type":"ListItem","position":2,"name":"Termine","item":"https:\/\/www.ecotechnology.at\/en\/termine\/"},{"@type":"ListItem","position":3,"name":"8. Nachhaltigkeitsbrunch &#8211; ESG 2026: Wie aus Reporting Wirkung entsteht"}]},{"@type":"WebSite","@id":"https:\/\/www.ecotechnology.at\/en\/#website","url":"https:\/\/www.ecotechnology.at\/en\/","name":"ecotechnology","description":"","publisher":{"@id":"https:\/\/www.ecotechnology.at\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecotechnology.at\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ecotechnology.at\/en\/#organization","name":"ecotechnology","url":"https:\/\/www.ecotechnology.at\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ecotechnology.at\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecotechnology.at\/wp-content\/uploads\/2023\/04\/ecolinks_logo_0.png","contentUrl":"https:\/\/www.ecotechnology.at\/wp-content\/uploads\/2023\/04\/ecolinks_logo_0.png","width":336,"height":128,"caption":"ecotechnology"},"image":{"@id":"https:\/\/www.ecotechnology.at\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/termine\/28499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/termine"}],"about":[{"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/types\/termine"}],"version-history":[{"count":6,"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/termine\/28499\/revisions"}],"predecessor-version":[{"id":28505,"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/termine\/28499\/revisions\/28505"}],"wp:attachment":[{"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/media?parent=28499"}],"wp:term":[{"taxonomy":"termin_category","embeddable":true,"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/termin_category?post=28499"},{"taxonomy":"cmcal_calendar","embeddable":true,"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/cmcal_calendar?post=28499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}