{"id":20808,"date":"2023-08-09T20:39:33","date_gmt":"2023-08-09T18:39:33","guid":{"rendered":"http:\/\/ecotechnology.wp.local\/termine\/the-green-expo-mexico-city\/"},"modified":"2023-08-09T20:39:33","modified_gmt":"2023-08-09T18:39:33","slug":"the-green-expo-mexico-city","status":"publish","type":"termine","link":"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/","title":{"rendered":"The Green Expo Mexico City"},"content":{"rendered":"<p>The Green Expo in Mexico Stadt bringt Firmen, Umweltexperten, Regierungsvertreter und weitere Fachleute aus verschiedenen Industrien zusammen, die sich \u00fcber Umwelttechnik austauschen und neue L\u00f6sungen f\u00fcr die Umwelttechnik entwickeln wollen. Die Messe und das gleichzeitig stattfindende Konferenzprogramm bieten die neusten Informationen \u00fcber zuk\u00fcnftige Trends f\u00fcr die Branche.<\/p>\n<p>Die The Green Expo findet an 3 Tagen von Dienstag, 07. September bis Donnerstag, 09. September 2021 in Mexico City statt.<\/p>\n","protected":false},"template":"","termin_category":[],"cmcal_calendar":[],"class_list":["post-20808","termine","type-termine","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Green Expo Mexico City - ecotechnology<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Green Expo Mexico City - ecotechnology\" \/>\n<meta property=\"og:description\" content=\"The Green Expo in Mexico Stadt bringt Firmen, Umweltexperten, Regierungsvertreter und weitere Fachleute aus verschiedenen Industrien zusammen, die sich \u00fcber Umwelttechnik austauschen und neue L\u00f6sungen f\u00fcr die Umwelttechnik entwickeln wollen. Die Messe und das gleichzeitig stattfindende Konferenzprogramm bieten die neusten Informationen \u00fcber zuk\u00fcnftige Trends f\u00fcr die Branche. Die The Green Expo findet an 3 Tagen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/\" \/>\n<meta property=\"og:site_name\" content=\"ecotechnology\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/\",\"url\":\"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/\",\"name\":\"The Green Expo Mexico City - ecotechnology\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecotechnology.at\/en\/#website\"},\"datePublished\":\"2023-08-09T18:39:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecotechnology.at\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Termine\",\"item\":\"https:\/\/www.ecotechnology.at\/en\/termine\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Green Expo Mexico City\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecotechnology.at\/en\/#website\",\"url\":\"https:\/\/www.ecotechnology.at\/en\/\",\"name\":\"ecotechnology\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ecotechnology.at\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecotechnology.at\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecotechnology.at\/en\/#organization\",\"name\":\"ecotechnology\",\"url\":\"https:\/\/www.ecotechnology.at\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.ecotechnology.at\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecotechnology.at\/wp-content\/uploads\/2023\/04\/ecolinks_logo_0.png\",\"contentUrl\":\"https:\/\/www.ecotechnology.at\/wp-content\/uploads\/2023\/04\/ecolinks_logo_0.png\",\"width\":336,\"height\":128,\"caption\":\"ecotechnology\"},\"image\":{\"@id\":\"https:\/\/www.ecotechnology.at\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Green Expo Mexico City - ecotechnology","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/","og_locale":"en_US","og_type":"article","og_title":"The Green Expo Mexico City - ecotechnology","og_description":"The Green Expo in Mexico Stadt bringt Firmen, Umweltexperten, Regierungsvertreter und weitere Fachleute aus verschiedenen Industrien zusammen, die sich \u00fcber Umwelttechnik austauschen und neue L\u00f6sungen f\u00fcr die Umwelttechnik entwickeln wollen. Die Messe und das gleichzeitig stattfindende Konferenzprogramm bieten die neusten Informationen \u00fcber zuk\u00fcnftige Trends f\u00fcr die Branche. Die The Green Expo findet an 3 Tagen [&hellip;]","og_url":"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/","og_site_name":"ecotechnology","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/","url":"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/","name":"The Green Expo Mexico City - ecotechnology","isPartOf":{"@id":"https:\/\/www.ecotechnology.at\/en\/#website"},"datePublished":"2023-08-09T18:39:33+00:00","breadcrumb":{"@id":"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecotechnology.at\/en\/termine\/the-green-expo-mexico-city\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecotechnology.at\/en\/"},{"@type":"ListItem","position":2,"name":"Termine","item":"https:\/\/www.ecotechnology.at\/en\/termine\/"},{"@type":"ListItem","position":3,"name":"The Green Expo Mexico City"}]},{"@type":"WebSite","@id":"https:\/\/www.ecotechnology.at\/en\/#website","url":"https:\/\/www.ecotechnology.at\/en\/","name":"ecotechnology","description":"","publisher":{"@id":"https:\/\/www.ecotechnology.at\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecotechnology.at\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ecotechnology.at\/en\/#organization","name":"ecotechnology","url":"https:\/\/www.ecotechnology.at\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ecotechnology.at\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecotechnology.at\/wp-content\/uploads\/2023\/04\/ecolinks_logo_0.png","contentUrl":"https:\/\/www.ecotechnology.at\/wp-content\/uploads\/2023\/04\/ecolinks_logo_0.png","width":336,"height":128,"caption":"ecotechnology"},"image":{"@id":"https:\/\/www.ecotechnology.at\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/termine\/20808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/termine"}],"about":[{"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/types\/termine"}],"version-history":[{"count":0,"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/termine\/20808\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/media?parent=20808"}],"wp:term":[{"taxonomy":"termin_category","embeddable":true,"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/termin_category?post=20808"},{"taxonomy":"cmcal_calendar","embeddable":true,"href":"https:\/\/www.ecotechnology.at\/en\/wp-json\/wp\/v2\/cmcal_calendar?post=20808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}